{"id":6774,"date":"2019-11-20T20:08:00","date_gmt":"2019-11-20T18:08:00","guid":{"rendered":"http:\/\/pc-direkthandel.de\/wordpress\/?post_type=product&#038;p=6774"},"modified":"2019-11-20T20:09:46","modified_gmt":"2019-11-20T18:09:46","slug":"grandstream-gxp-2170","status":"publish","type":"product","link":"http:\/\/pc-direkthandel.de\/wordpress\/product\/grandstream-gxp-2170\/","title":{"rendered":"Grandstream GXP-2170"},"content":{"rendered":"<p>Das GXP2170 ist ein hochperformantes IP Telefon und das ideale Werkzeug f\u00fcr alle Anforderungen mit hohem Gesr\u00e4chsvolumen. Dieses Top-of-the-Line Business HD-IP-Telefon pr\u00e4sentiert auf einem 4,3\u201d Farbdisplay alle wichtigen Informationen und stellt 12 Leitungstasten und bis zu 6 SIP Konten zur Verf\u00fcgung. Nat\u00fcrlich verf\u00fcgt das GXP2170 \u00fcber zwei Gigabit Netzwerkanschl\u00fcsse mit PoE, F\u00fcr die Anbindung mobiler Endger\u00e4te oder eines Headsets h\u00e4lt es eine integrierte Bluetooth-Schnittstelle bereit. Am Telefon selbst k\u00f6nnen bis zu 48 Kurz-\/BLF-Funktionen programmiert werden. Durch den Anschluss von bis zu vier optionalen LCD-Erweiterungsmodulen GXP2200EXT k\u00f6nnen max. 160 weitere Eintr\u00e4ge realisiert werden. Das GXP2170 ist die ideale Begleitung f\u00fcr alle optisch und qualitativ anspruchsvollen Anwender, die modernste Kommunikationsmittel f\u00fcr sich zu Nutzen wissen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das GXP2170 ist ein hochperformantes IP Telefon und das ideale Werkzeug f\u00fcr alle Anforderungen mit hohem Gesr\u00e4chsvolumen. Dieses Top-of-the-Line Business HD-IP-Telefon pr\u00e4sentiert auf einem 4,3\u201d Farbdisplay alle wichtigen Informationen und stellt 12 Leitungstasten und bis zu 6 SIP Konten zur Verf\u00fcgung. Nat\u00fcrlich verf\u00fcgt das GXP2170 \u00fcber zwei Gigabit Netzwerkanschl\u00fcsse mit PoE, F\u00fcr die Anbindung mobiler [&hellip;]<\/p>\n","protected":false},"featured_media":6775,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[408],"product_tag":[],"class_list":["post-6774","product","type-product","status-publish","has-post-thumbnail","product_cat-voip-grandstream","first","instock","shipping-taxable","product-type-external"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/product\/6774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/comments?post=6774"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/media\/6775"}],"wp:attachment":[{"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/media?parent=6774"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/product_brand?post=6774"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/product_cat?post=6774"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/product_tag?post=6774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}