{"id":6205,"date":"2019-11-15T20:28:02","date_gmt":"2019-11-15T18:28:02","guid":{"rendered":"http:\/\/pc-direkthandel.de\/wordpress\/?post_type=product&#038;p=6205"},"modified":"2019-11-15T20:29:22","modified_gmt":"2019-11-15T18:29:22","slug":"motorola-it-6-1x","status":"publish","type":"product","link":"http:\/\/pc-direkthandel.de\/wordpress\/product\/motorola-it-6-1x\/","title":{"rendered":"Motorola IT.6.1X"},"content":{"rendered":"<p>Ein unglaublich d\u00fcnnes Schnurlostelefon IT.6.1X ist das ultimative Festnetztelefon. Das Mobilteil wird mit einem echten Metallrahmen umfasst, was seine Robustheit und seine nahtlose markante Form auzeichnet. Die Kristallbasis tr\u00e4gt zur Einzigartigkeit und Eleganz, aus jedem Blickwinkel bei.<\/p>\n<p><b>Highlights:<\/b><br \/>\n&#8211; Digitales Schnurlostelefon<br \/>\n&#8211; Schlankes Mobilteil-Design<br \/>\n&#8211; Gro\u00dfes 5,59 cm (2,2 Zoll) 65K Farbdisplay mit wei\u00dfer Hinterundbeleuchtung<br \/>\n&#8211; 100 Namen und Nummern Telefonbuch<br \/>\n&#8211; Freisprechen am Mobilteil<br \/>\n&#8211; Studioproduzierte Klingelt\u00f6ne<br \/>\n&#8211; Kristallbasis mit hinterbeleuchteten Tasten<br \/>\n&#8211; Lasergefr\u00e4ste und beleuchtete Tastatur<br \/>\n&#8211; ECO PLUS- Energiesparmodus<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein unglaublich d\u00fcnnes Schnurlostelefon IT.6.1X ist das ultimative Festnetztelefon. Das Mobilteil wird mit einem echten Metallrahmen umfasst, was seine Robustheit und seine nahtlose markante Form auzeichnet. Die Kristallbasis tr\u00e4gt zur Einzigartigkeit und Eleganz, aus jedem Blickwinkel bei. Highlights: &#8211; Digitales Schnurlostelefon &#8211; Schlankes Mobilteil-Design &#8211; Gro\u00dfes 5,59 cm (2,2 Zoll) 65K Farbdisplay mit wei\u00dfer Hinterundbeleuchtung [&hellip;]<\/p>\n","protected":false},"featured_media":6206,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[376],"product_tag":[],"class_list":["post-6205","product","type-product","status-publish","has-post-thumbnail","product_cat-dect-motorola-telekom","first","instock","shipping-taxable","product-type-external"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/product\/6205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/comments?post=6205"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/media\/6206"}],"wp:attachment":[{"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/media?parent=6205"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/product_brand?post=6205"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/product_cat?post=6205"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/pc-direkthandel.de\/wordpress\/wp-json\/wp\/v2\/product_tag?post=6205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}